{"id":1939,"date":"2020-11-25T10:45:41","date_gmt":"2020-11-25T15:45:41","guid":{"rendered":"https:\/\/iceriversustainablesolutions.com\/?page_id=1939"},"modified":"2021-07-12T09:30:38","modified_gmt":"2021-07-12T13:30:38","slug":"bmp-recycling","status":"publish","type":"page","link":"https:\/\/iceriversustainablesolutions.com\/fr\/bmp-recycling\/","title":{"rendered":"BMP Recycling"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime; background_enable_color=\u00a0\u00bboff\u00a0\u00bb use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bbrgba(216,216,216,0)\u00a0\u00bb background_color_gradient_end=\u00a0\u00bb#171e43&Prime; background_color_gradient_start_position=\u00a0\u00bb40%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/iceriversustainablesolutions.com\/\/wp-content\/uploads\/2020\/09\/OspreyFarms-hero2.jpg\u00a0\u00bb background_position=\u00a0\u00bbtop_center\u00a0\u00bb custom_padding=\u00a0\u00bb350px||50px||false|false\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.4.8&Prime; background_layout=\u00a0\u00bbdark\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb]<\/p>\n<h1>BMP Recycling <\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; next_background_color=\u00a0\u00bb#ffffff\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime; background_color=\u00a0\u00bb#171e43&Prime; background_image=\u00a0\u00bbhttps:\/\/iceriversustainablesolutions.com\/\/wp-content\/uploads\/2020\/09\/Home-Water-Rays.png\u00a0\u00bb background_position=\u00a0\u00bbtop_center\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb bottom_divider_style=\u00a0\u00bbwaves\u00a0\u00bb bottom_divider_flip=\u00a0\u00bbhorizontal\u00a0\u00bb][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_row _builder_version=\u00a0\u00bb4.4.8&Prime; custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime; custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.4.8&Prime; max_width=\u00a0\u00bb900px\u00a0\u00bb]<\/p>\n<h2>Nous sommes une usine de recyclage du plastique novatrice qui produit du plastique PET enti\u00e8rement recycl\u00e9. <\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.9.7&Prime; hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>Notre processus est exceptionnel puisque le PET recycl\u00e9 que nous produisons peut \u00e0 son tour \u00eatre recycl\u00e9, et ce, \u00e0 l\u2019infini. Nous achetons des ballots de plastique PET des usines de recyclage municipales partout au Canada et dans le nord des \u00c9tats-Unis. Nous retirons le contenu \u00e9tranger, puis traitons et trions les mat\u00e9riaux selon leur couleur. C\u2019est ainsi que nous produisons le granul\u00e9 de plastique que nous envoyons au centre Ice River Feversham, qui le purifie pour obtenir un plastique de qualit\u00e9 alimentaire que nous pouvons ensuite utiliser pour fabriquer de nouveaux contenants pour les aliments, y compris nos bouteilles bleues et vertes enti\u00e8rement recycl\u00e9es.<\/p>\n<p>Nous produisons un granul\u00e9 de plastique transparent et bleu que nous utilisons pour fabriquer nos bouteilles enti\u00e8rement recycl\u00e9es.<\/p>\n<p>Auparavant, le granul\u00e9 vert \u00e9tait recycl\u00e9 en boucle ouverte ou envoy\u00e9 dans les sites d\u2019enfouissement. Aujourd\u2019hui, nous l\u2019utilisons pour fabriquer nos bouteilles vertes.<\/p>\n<h3>Accro\u00eetre nos activit\u00e9s de recyclage.<\/h3>\n<p>Notre usine recycle 55\u00a0millions de livres de plastique PET chaque ann\u00e9e; celui-ci provient principalement du programme de bo\u00eete bleue de l\u2019Ontario. Nous sommes toujours heureux de voir nos propres bouteilles nous revenir pour \u00eatre recycl\u00e9es \u00e0 nouveau. Notre croissance nous permet de recycler de plus en plus de types d\u2019emballage durable.<\/p>\n<h3>Trouver de nouvelles solutions de recyclage.<\/h3>\n<p>Le contenant double coque thermoform\u00e9 est un type d\u2019emballage de qualit\u00e9 alimentaire pr\u00e9form\u00e9 qui, normalement, ne peut pas \u00eatre recycl\u00e9. Nous avons convaincu les installations de r\u00e9cup\u00e9ration de mat\u00e9riaux d\u2019inclure ce type d\u2019emballage dans nos ballots de PET pour que nous puissions l\u2019utiliser dans le recyclage menant \u00e0 la fabrication de nos bouteilles enti\u00e8rement recycl\u00e9es. <strong>Cette initiative nous permet de recycler des millions de livres suppl\u00e9mentaires de plastique qui serait autrement envoy\u00e9 dans les sites d\u2019enfouissement chaque ann\u00e9e.<\/strong><\/p>\n<h3>Nous sommes extr\u00eamement fiers de notre r\u00e9sine PET<\/h3>\n<p>Notre r\u00e9sine PET recycl\u00e9e est faite de plastique recycl\u00e9 \u00e0 100\u00a0%. Gr\u00e2ce \u00e0 notre processus de recyclage en circuit ferm\u00e9, la r\u00e9sine que nous vendons est utilis\u00e9e pour fabriquer des emballages durables qui nous reviennent pour que nous puissions les retransformer en r\u00e9sine \u00e0 l\u2019infini.<\/p>\n<h3>Tout commence par une approche \u00e9cologique<\/h3>\n<p>Pour cr\u00e9er notre r\u00e9sine de grande qualit\u00e9, nous achetons d\u2019abord des ballots de plastique PET par le biais des programmes de recyclage municipaux. Nous trions, broyons, lavons et purifions le plastique afin de former un granul\u00e9 de plastique de qualit\u00e9 alimentaire. En choisissant d\u2019utiliser du plastique recycl\u00e9, nous diminuons la demande de plastique vierge, en plus d\u2019utiliser moins d\u2019\u00e9nergie et moins d\u2019eau que ce qui est n\u00e9cessaire pour fabriquer de la r\u00e9sine vierge.<\/p>\n<p>Sp\u00e9cifications de la r\u00e9sine PET recycl\u00e9e\u00a0:<\/p>\n<ul>\n<li>R\u00e9sine PET enti\u00e8rement recycl\u00e9e, homologu\u00e9e par l\u2019ACIA et la FDA<\/li>\n<li>R\u00e9sine standard en stock (possibilit\u00e9 de personnaliser les commandes de grande quantit\u00e9 en fonction des besoins du client)<\/li>\n<li>R\u00e9sine exp\u00e9di\u00e9e dans des conteneurs souples de 1 Mt (des frais de conteneur et de palette s\u2019appliquent)<\/li>\n<li>Offerte en bleu et en vert<\/li>\n<li>FAB Feversham, Ontario<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.4.8&Prime; custom_margin=\u00a0\u00bb100px||||false|false\u00a0\u00bb]<\/p>\n<h2>LAISSEZ-NOUS VOUS AIDER DANS VOTRE PARCOURS DE DURABILIT\u00c9<\/h2>\n<p>BMP Recycling peut rendre votre processus de fabrication plus \u00e9cologique gr\u00e2ce \u00e0 une r\u00e9sine PET recycl\u00e9e de qualit\u00e9 sup\u00e9rieure offerte en bleu ou en vert transparent.<\/p>\n<p>Pour en apprendre davantage ou pour obtenir un devis, communiquez avec nous.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbmailto:info@iceriversprings.com\u00a0\u00bb button_text=\u00a0\u00bbEnvoyer un courriel\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime;][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_image src=\u00a0\u00bbhttps:\/\/iceriversustainablesolutions.com\/wp-content\/uploads\/2020\/12\/BMP-Recycling-Logo.png\u00a0\u00bb alt=\u00a0\u00bbBMP Recycling Logo\u00a0\u00bb title_text=\u00a0\u00bbBMP-Recycling-Logo\u00a0\u00bb show_bottom_space=\u00a0\u00bboff\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime; background_enable_image=\u00a0\u00bboff\u00a0\u00bb background_size=\u00a0\u00bbcontain\u00a0\u00bb][\/et_pb_image][et_pb_image src=\u00a0\u00bbhttps:\/\/iceriversustainablesolutions.com\/wp-content\/uploads\/2020\/09\/bmp-crystal.png\u00a0\u00bb alt=\u00a0\u00bbA\u00a0\u00bb title_text=\u00a0\u00bbbmp-crystal\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime; custom_margin=\u00a0\u00bb60px||||false|false\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_image src=\u00a0\u00bbhttps:\/\/iceriversustainablesolutions.com\/wp-content\/uploads\/2021\/06\/blue-pet.jpeg\u00a0\u00bb alt=\u00a0\u00bbRecycled plastic in 2 forms. Blue pellets and clear shredded plastic\u00a0\u00bb title_text=\u00a0\u00bbblue-pet\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime;][\/et_pb_image][et_pb_image src=\u00a0\u00bbhttps:\/\/iceriversustainablesolutions.com\/wp-content\/uploads\/2021\/06\/Ice-river-green-flakes.jpeg\u00a0\u00bb alt=\u00a0\u00bbRecycled plastic in 2 forms. Green Pellets and green flakes\u00a0\u00bb title_text=\u00a0\u00bbIce-river-green-flakes\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime; custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||51px|||\u00a0\u00bb global_module=\u00a0\u00bb1902&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_image src=\u00a0\u00bbhttps:\/\/iceriversustainablesolutions.com\/\/wp-content\/uploads\/2018\/06\/logo-ir-footer.png\u00a0\u00bb title_text=\u00a0\u00bblogo-ir-footer\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime; max_width=\u00a0\u00bb188px\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.4.8&Prime; max_width=\u00a0\u00bb750px\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.4.8&Prime; header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb]<\/p>\n<h3>Prenez part au changement. Abonnez-vous \u00e0 notre infolettre.<\/h3>\n<p>Notre gamme de produits durables et nos entreprises continuent de grandir. Inscrivez-vous pour recevoir les derni\u00e8res nouvelles concernant nos innovations par courriel. (Nous communiquerons avec vous uniquement si nous avons des nouvelles importantes. Nous n\u2019aimons pas les d\u00e9chets \u00e9lectroniques non plus.)[\/et_pb_text][et_pb_contact_form captcha=\u00a0\u00bboff\u00a0\u00bb submit_button_text=\u00a0\u00bbEnvoyer\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_contact_field field_id=\u00a0\u00bbFirst-Name\u00a0\u00bb field_title=\u00a0\u00bbPr\u00e9nom\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime; button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbLast-Name\u00a0\u00bb field_title=\u00a0\u00bbNom de famille\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime; button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbEmail\u00a0\u00bb field_title=\u00a0\u00bbAdresse courriel\u00a0\u00bb field_type=\u00a0\u00bbemail\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime; button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbField_4&Prime; field_title=\u00a0\u00bb \u00a0\u00bb field_type=\u00a0\u00bbcheckbox\u00a0\u00bb checkbox_options=\u00a0\u00bb%91{%22value%22:%22En nous donnant votre adresse courriel, vous acceptez de recevoir des messages \u00e9lectroniques de la part de Ice River Sustainable Solutions contenant des renseignements, des infolettres, des offres et des promotions. Vous pouvez annuler votre consentement \u00e0 tout moment en cliquant sur \u00ab\u2009Se d\u00e9sabonner\u2009\u00bb \u00e0 la fin d\u2019un courriel que nous vous avons envoy\u00e9 ou en communiquant avec nous.%22,%22checked%22:0,%22dragID%22:-1}%93&Prime; fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime; custom_css_main_element=\u00a0\u00bbfont-size: 12px;\u00a0\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][et_pb_text _builder_version=\u00a0\u00bb4.4.8&Prime; text_font_size=\u00a0\u00bb12px\u00a0\u00bb]<\/p>\n<p>Veuillez consulter notre\u00a0<a href=\"\/fr\/privacy-policy\/\">politique de confidentialit\u00e9<\/a>\u00a0ou communiquer avec nous \u00e0 l\u2019adresse suivante\u00a0: Ice River Sustainable Solutions 485387 30 Sideroad  Shelburne, ON L9V 3N5.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_4,1_4&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime; border_width_top=\u00a0\u00bb1px\u00a0\u00bb border_color_top=\u00a0\u00bb#F4F4F4&Prime; border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#F4F4F4&Prime;][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.4.8&Prime; custom_margin=\u00a0\u00bb||10px||false|false\u00a0\u00bb]<strong>SUIVEZ-NOUS<\/strong>[\/et_pb_text][et_pb_social_media_follow _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_social_media_follow_network social_network=\u00a0\u00bbfacebook\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.facebook.com\/IceRiverSustainableSolutions\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime; background_color=\u00a0\u00bb#3b5998&Prime; follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00a0\u00bblinkedin\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.linkedin.com\/company\/671667\/admin\/\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime; background_color=\u00a0\u00bb#007bb6&Prime; follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]linkedin[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00a0\u00bbinstagram\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.instagram.com\/iceriversustainablesolutions\/\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime; background_color=\u00a0\u00bb#ea2c59&Prime; follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00a0\u00bbyoutube\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.youtube.com\/channel\/UCg8jVH7oAyS7-oaYS0LQwBg\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.8&Prime; background_color=\u00a0\u00bb#a82400&Prime; follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]youtube[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][et_pb_text _builder_version=\u00a0\u00bb4.4.8&Prime; custom_margin=\u00a0\u00bb||10px||false|false\u00a0\u00bb]<strong>\u00c0 propos de nous<\/strong><br \/>\nIce River Sustainable Solutions est une entreprise familiale canadienne qui se consacre \u00e0 l\u2019embouteillage de l\u2019eau de source naturelle en misant sur la durabilit\u00e9 et le recyclage du plastique PET. Nous collaborons avec d\u2019autres entreprises afin de trouver des fa\u00e7ons cr\u00e9atives de r\u00e9utiliser et de recycler les bouteilles en plastique en concevant des emballages et des articles \u00e9cologiques fabriqu\u00e9s enti\u00e8rement en plastique recycl\u00e9.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.4.8&Prime; text_font_size=\u00a0\u00bb14px\u00a0\u00bb]<strong>PLUS D\u2019INFORMATION<br \/>\n<\/strong><\/p>\n<p><a href=\"\/fr\/our-innovations\/\">Nos innovations<\/a><br \/>\n<a href=\"\/fr\/our-commitment\/\">Notre engagement<\/a><br \/>\n<a href=\"\/fr\/our-companies\/\">Nos entreprises<\/a><br \/>\n<a href=\"\/fr\/our-culture\/\">Notre culture<\/a><br \/>\n<a href=\"\/fr\/careers\/\">Nos offres d\u2019emploi<\/a><br \/>\n<a href=\"\/fr\/contact-us\/\">Nous joindre<\/a>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.4.8&Prime;]<\/p>\n<p><strong>ICE RIVER SUSTAINABLE SOLUTIONS<\/strong><br \/> 485387 Sideroad 30<br \/> Dufferin County Road 11<br \/> Shelburne ON Canada<br \/> L9V 3N5<\/p>\n<p><a href=\"tel:18007647336\">1-844-SO-GREEN<\/a><br \/> (1-844-764-7336)<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/iceriversustainablesolutions.com\/\/wp-content\/uploads\/2018\/06\/logo-made-in-canada.png\u00a0\u00bb alt=\u00a0\u00bbFabrique au Canada logo\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.7&Prime; max_width=\u00a0\u00bb91px\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.4.8&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.4.8&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb]Copyright \u00a9 2020. Ice River Sustainable Solutions. Tous droits r\u00e9serv\u00e9s.<\/p>\n<p><a href=\"\/fr\/accessibility\/\">Accessibilit\u00e9<\/a> | <a href=\"\/fr\/terms-of-use\/\">Conditions g\u00e9n\u00e9rales<\/a> | <a href=\"\/fr\/privacy-policy\/\">Politique de confidentialit\u00e9<\/a>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BMP Recycling Nous sommes une usine de recyclage du plastique novatrice qui produit du plastique PET enti\u00e8rement recycl\u00e9. Notre processus est exceptionnel puisque le PET recycl\u00e9 que nous produisons peut \u00e0 son tour \u00eatre recycl\u00e9, et ce, \u00e0 l\u2019infini. Nous achetons des ballots de plastique PET des usines de recyclage municipales partout au Canada et [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1939","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BMP Recycling - Ice River Sustainable Solutions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iceriversustainablesolutions.com\/fr\/bmp-recycling\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BMP Recycling - Ice River Sustainable Solutions\" \/>\n<meta property=\"og:description\" content=\"BMP Recycling Nous sommes une usine de recyclage du plastique novatrice qui produit du plastique PET enti\u00e8rement recycl\u00e9. Notre processus est exceptionnel puisque le PET recycl\u00e9 que nous produisons peut \u00e0 son tour \u00eatre recycl\u00e9, et ce, \u00e0 l\u2019infini. Nous achetons des ballots de plastique PET des usines de recyclage municipales partout au Canada et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iceriversustainablesolutions.com\/fr\/bmp-recycling\/\" \/>\n<meta property=\"og:site_name\" content=\"Ice River Sustainable Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-12T13:30:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BMP Recycling - Ice River Sustainable Solutions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iceriversustainablesolutions.com\/fr\/bmp-recycling\/","og_locale":"fr_FR","og_type":"article","og_title":"BMP Recycling - Ice River Sustainable Solutions","og_description":"BMP Recycling Nous sommes une usine de recyclage du plastique novatrice qui produit du plastique PET enti\u00e8rement recycl\u00e9. Notre processus est exceptionnel puisque le PET recycl\u00e9 que nous produisons peut \u00e0 son tour \u00eatre recycl\u00e9, et ce, \u00e0 l\u2019infini. Nous achetons des ballots de plastique PET des usines de recyclage municipales partout au Canada et [&hellip;]","og_url":"https:\/\/iceriversustainablesolutions.com\/fr\/bmp-recycling\/","og_site_name":"Ice River Sustainable Solutions","article_modified_time":"2021-07-12T13:30:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/iceriversustainablesolutions.com\/fr\/bmp-recycling\/","url":"https:\/\/iceriversustainablesolutions.com\/fr\/bmp-recycling\/","name":"BMP Recycling - Ice River Sustainable Solutions","isPartOf":{"@id":"https:\/\/iceriversustainablesolutions.com\/fr\/#website"},"datePublished":"2020-11-25T15:45:41+00:00","dateModified":"2021-07-12T13:30:38+00:00","breadcrumb":{"@id":"https:\/\/iceriversustainablesolutions.com\/fr\/bmp-recycling\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iceriversustainablesolutions.com\/fr\/bmp-recycling\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/iceriversustainablesolutions.com\/fr\/bmp-recycling\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iceriversustainablesolutions.com\/fr\/"},{"@type":"ListItem","position":2,"name":"BMP Recycling"}]},{"@type":"WebSite","@id":"https:\/\/iceriversustainablesolutions.com\/fr\/#website","url":"https:\/\/iceriversustainablesolutions.com\/fr\/","name":"Ice River Sustainable Solutions","description":"We&#039;re more than just a bottled water company.","publisher":{"@id":"https:\/\/iceriversustainablesolutions.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iceriversustainablesolutions.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/iceriversustainablesolutions.com\/fr\/#organization","name":"Ice River Sustainable Solutions","url":"https:\/\/iceriversustainablesolutions.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/iceriversustainablesolutions.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Ice River Sustainable Solutions"},"image":{"@id":"https:\/\/iceriversustainablesolutions.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/iceriversustainablesolutions.com\/fr\/wp-json\/wp\/v2\/pages\/1939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iceriversustainablesolutions.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iceriversustainablesolutions.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iceriversustainablesolutions.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/iceriversustainablesolutions.com\/fr\/wp-json\/wp\/v2\/comments?post=1939"}],"version-history":[{"count":0,"href":"https:\/\/iceriversustainablesolutions.com\/fr\/wp-json\/wp\/v2\/pages\/1939\/revisions"}],"wp:attachment":[{"href":"https:\/\/iceriversustainablesolutions.com\/fr\/wp-json\/wp\/v2\/media?parent=1939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}